{"id":7265,"date":"2023-06-12T18:30:00","date_gmt":"2023-06-12T18:30:00","guid":{"rendered":"https:\/\/cjesh.org\/dev\/?p=7265"},"modified":"2023-06-19T13:05:30","modified_gmt":"2023-06-19T13:05:30","slug":"rapport-annuel-2022-2023","status":"publish","type":"post","link":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/","title":{"rendered":"Rapport annuel 2022-2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7265\" class=\"elementor elementor-7265\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d0969 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d0969\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-641d92ae\" data-id=\"641d92ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e937d06 elementor-widget elementor-widget-text-editor\" data-id=\"3e937d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>L&#8217;ann\u00e9e 2022-2023 qui marquait le 25e anniversaire du Carrefour jeunesse-emploi Saint-Hubert s&#8217;est av\u00e9r\u00e9e riche en nouveaut\u00e9s, projets et d\u00e9fis !&nbsp;<\/strong><\/h3>\n<div style=\"text-align: center;\"><strong>Cette ann\u00e9e, c&#8217;est 1484 jeunes et jeunes adultes qui ont \u00e9t\u00e9 rejoints.&nbsp;<\/strong><strong style=\"text-align: center; color: var( --e-global-color-secondary );\">C&#8217;est donc avec plaisir et fiert\u00e9 que nous vous pr\u00e9sentons un aper\u00e7u de notre travail dans le rapport annuel 2022-2023.&nbsp;<\/strong><\/div>\n<p style=\"text-align: center;\"><strong>&nbsp;<\/strong><\/p>\n<p style=\"text-align: center;\">\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-898e445 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"898e445\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7271fe\" data-id=\"e7271fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd8600f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bd8600f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2023\/06\/RAPPORT_ANNUEL_2022-2023_taille_reduite-1.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-readme\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulter le rapport annuel<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l&#8217;ann\u00e9e qui s&#8217;est termin\u00e9e en mars 2023. <\/p>\n","protected":false},"author":5,"featured_media":7282,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-7265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-de-blogue"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l&#039;ann\u00e9e qui s&#039;est termin\u00e9e en mars 2023.\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"J\u00e9r\u00f4me\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CJESH - Le CJESH, la porte d&#039;entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rapport annuel 2022-2023 - # CJESH\" \/>\n\t\t<meta property=\"og:description\" content=\"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l&#039;ann\u00e9e qui s&#039;est termin\u00e9e en mars 2023.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-12T18:30:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-19T13:05:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rapport annuel 2022-2023 - # CJESH\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l&#039;ann\u00e9e qui s&#039;est termin\u00e9e en mars 2023.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#blogposting\",\"name\":\"Rapport annuel 2022-2023 - # CJESH\",\"headline\":\"Rapport annuel 2022-2023\",\"author\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Banniere_siteweb_RA_22-23.png\",\"width\":2104,\"height\":610},\"datePublished\":\"2023-06-12T18:30:00+00:00\",\"dateModified\":\"2023-06-19T13:05:30+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#webpage\"},\"articleSection\":\"Articles de blogue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cjesh.org\\\/dev\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"name\":\"Articles de blogue\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"position\":2,\"name\":\"Articles de blogue\",\"item\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#listItem\",\"name\":\"Rapport annuel 2022-2023\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#listItem\",\"position\":3,\"name\":\"Rapport annuel 2022-2023\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"name\":\"Articles de blogue\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\",\"name\":\"CJESH\",\"description\":\"Le CJESH, la porte d'entr\\u00e9e pour les 16 \\u00e0 35 ans de Saint-Hubert.\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/CJESH_Logo_Officiel_noir-2048x978-1.png\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/\",\"name\":\"J\\u00e9r\\u00f4me\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7888bff20ae315f9f8ded88b9b8de8922ae8a8ebe5a576bcda9d468ebde545d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"J\\u00e9r\\u00f4me\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#webpage\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/\",\"name\":\"Rapport annuel 2022-2023 - # CJESH\",\"description\":\"Voici notre rapport annuel. On y trouve une pr\\u00e9sentation de nos activit\\u00e9s et services pour l'ann\\u00e9e qui s'est termin\\u00e9e en mars 2023.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Banniere_siteweb_RA_22-23.png\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#mainImage\",\"width\":2104,\"height\":610},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/rapport-annuel-2022-2023\\\/#mainImage\"},\"datePublished\":\"2023-06-12T18:30:00+00:00\",\"dateModified\":\"2023-06-19T13:05:30+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#website\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/\",\"name\":\"CJESH\",\"description\":\"Le CJESH, la porte d'entr\\u00e9e pour les 16 \\u00e0 35 ans de Saint-Hubert.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rapport annuel 2022-2023 - # CJESH","description":"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l'ann\u00e9e qui s'est termin\u00e9e en mars 2023.","canonical_url":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/","robots":"noindex, nofollow, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#blogposting","name":"Rapport annuel 2022-2023 - # CJESH","headline":"Rapport annuel 2022-2023","author":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/cjesh.org\/dev\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2023\/06\/Banniere_siteweb_RA_22-23.png","width":2104,"height":610},"datePublished":"2023-06-12T18:30:00+00:00","dateModified":"2023-06-19T13:05:30+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#webpage"},"isPartOf":{"@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#webpage"},"articleSection":"Articles de blogue"},{"@type":"BreadcrumbList","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev#listItem","position":1,"name":"Accueil","item":"https:\/\/cjesh.org\/dev","nextItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","name":"Articles de blogue"}},{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","position":2,"name":"Articles de blogue","item":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#listItem","name":"Rapport annuel 2022-2023"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#listItem","position":3,"name":"Rapport annuel 2022-2023","previousItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","name":"Articles de blogue"}}]},{"@type":"Organization","@id":"https:\/\/cjesh.org\/dev\/#organization","name":"CJESH","description":"Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","url":"https:\/\/cjesh.org\/dev\/","logo":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2021\/11\/CJESH_Logo_Officiel_noir-2048x978-1.png","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#organizationLogo"},"image":{"@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author","url":"https:\/\/cjesh.org\/dev\/author\/admin1\/","name":"J\u00e9r\u00f4me","image":{"@type":"ImageObject","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f7888bff20ae315f9f8ded88b9b8de8922ae8a8ebe5a576bcda9d468ebde545d?s=96&d=mm&r=g","width":96,"height":96,"caption":"J\u00e9r\u00f4me"}},{"@type":"WebPage","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#webpage","url":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/","name":"Rapport annuel 2022-2023 - # CJESH","description":"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l'ann\u00e9e qui s'est termin\u00e9e en mars 2023.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/cjesh.org\/dev\/#website"},"breadcrumb":{"@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#breadcrumblist"},"author":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2023\/06\/Banniere_siteweb_RA_22-23.png","@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#mainImage","width":2104,"height":610},"primaryImageOfPage":{"@id":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/#mainImage"},"datePublished":"2023-06-12T18:30:00+00:00","dateModified":"2023-06-19T13:05:30+00:00"},{"@type":"WebSite","@id":"https:\/\/cjesh.org\/dev\/#website","url":"https:\/\/cjesh.org\/dev\/","name":"CJESH","description":"Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/cjesh.org\/dev\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"CJESH - Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","og:type":"article","og:title":"Rapport annuel 2022-2023 - # CJESH","og:description":"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l'ann\u00e9e qui s'est termin\u00e9e en mars 2023.","og:url":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/","article:published_time":"2023-06-12T18:30:00+00:00","article:modified_time":"2023-06-19T13:05:30+00:00","twitter:card":"summary","twitter:title":"Rapport annuel 2022-2023 - # CJESH","twitter:description":"Voici notre rapport annuel. On y trouve une pr\u00e9sentation de nos activit\u00e9s et services pour l'ann\u00e9e qui s'est termin\u00e9e en mars 2023."},"aioseo_meta_data":{"post_id":"7265","title":"#post_title #separator_sa # #site_title","description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-12 13:30:56","updated":"2025-06-04 10:27:39","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cjesh.org\/dev\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/\" title=\"Articles de blogue\">Articles de blogue<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRapport annuel 2022-2023\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/cjesh.org\/dev"},{"label":"Articles de blogue","link":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/"},{"label":"Rapport annuel 2022-2023","link":"https:\/\/cjesh.org\/dev\/rapport-annuel-2022-2023\/"}],"_links":{"self":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/7265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/comments?post=7265"}],"version-history":[{"count":29,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/7265\/revisions"}],"predecessor-version":[{"id":7307,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/7265\/revisions\/7307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/media\/7282"}],"wp:attachment":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/media?parent=7265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/categories?post=7265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/tags?post=7265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}