{"id":4998,"date":"2021-10-29T19:51:00","date_gmt":"2021-10-29T19:51:00","guid":{"rendered":"https:\/\/cjesh.org\/dev\/?p=4998"},"modified":"2022-01-14T15:09:32","modified_gmt":"2022-01-14T15:09:32","slug":"est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels","status":"publish","type":"post","link":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/","title":{"rendered":"Est-il possible de gagner sa vie dans le domaine des arts visuels?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4998\" class=\"elementor elementor-4998\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d0969 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d0969\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-641d92ae\" data-id=\"641d92ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e937d06 elementor-widget elementor-widget-text-editor\" data-id=\"3e937d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\">Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.<\/p>\n<p><br \/>Il est vrai que la majorit\u00e9 des artistes en arts visuels \u0153uvrent comme travailleur autonome, \u00e0 contrat ou \u00e0 la pige. Au Qu\u00e9bec, selon Statistiques Canada en 2015, ce serait 67% d\u2019entre eux qui travailleraient \u00e0 leur compte. De ceux-ci, selon l\u2019Institut de la statistique du Qu\u00e9bec, ce serait pr\u00e8s de 60% qui gagneraient un revenu annuel inf\u00e9rieur \u00e0 30 000$ et ce ne serait que 13% qui seraient parvenus \u00e0 gagner un revenu annuel sup\u00e9rieur \u00e0 59 000$ en 2010.\u00a0La diff\u00e9rence entre ceux qui gagnent mieux et moins bien leur vie rel\u00e8ve du\u00a0temps qu\u2019ils d\u00e9dient \u00e0 la promotion de leur carri\u00e8re artistique et \u00e0 la\u00a0participation \u00e0 des activit\u00e9s r\u00e9mun\u00e9r\u00e9es connexes.<\/p>\n<p><br \/>En effet, pour promouvoir ta carri\u00e8re artistique, il sera primordial que tu consacres autant de temps \u00e0 la diffusion de tes \u0153uvres qu\u2019\u00e0 la conception. Pour ce faire, le premier outil que tu devras avoir \u00e0 ta disposition, ce sera ton portfolio. Il s\u2019agit d\u2019un dossier d\u2019artiste dans lequel on doit retrouver : ta lettre de pr\u00e9sentation, ton curriculum vitae, ta d\u00e9marche artistique, ta biographie, ton dossier de presse, s\u2019il y a lieu, ainsi qu\u2019une pr\u00e9sentation de ce que tu es capable de faire. Ce dernier te permettra de soumettre ta candidature lors d\u2019expositions, de symposiums, de r\u00e9sidences artistiques et de concours. Il te permettra \u00e9galement de faire des demandes de bourses et de subventions et d\u2019obtenir de la repr\u00e9sentation dans des galeries d\u2019art et des<br \/>commerces. L\u2019utilisation des r\u00e9seaux sociaux, l\u2019adh\u00e9sion \u00e0 des regroupements et des associations artistiques et la cr\u00e9ation d\u2019un site internet sont aussi des incontournables pour se faire conna\u00eetre. Il faut toutefois prendre en consid\u00e9ration que tu ne seras pas le seul \u00e0 chercher \u00e0 te faire une place dans le domaine artistique. Il est donc important de d\u00e9finir qui sera ton public cible et de trouver ce qui te d\u00e9marquera des autres artistes.<\/p>\n<p><br \/>Pour pouvoir vivre de son art, il est \u00e9galement possible de diversifier ses sources de revenus en donnant des cours d\u2019art, en vendant des produits d\u00e9riv\u00e9s, en utilisant ses droits d\u2019auteur ou en louant ses \u0153uvres pour des \u00e9v\u00e8nements ou des expositions.<\/p>\n<p><br \/>Pour ceux qui pourraient avoir besoin de plus de s\u00e9curit\u00e9 financi\u00e8re, plusieurs m\u00e9tiers existent dans le domaine des arts visuels. Pour n\u2019en nommer que quelques-uns, on y retrouve, entre autres, les graphistes, les illustrateurs, les animateurs 2D et 3D et les designers d\u2019int\u00e9rieur.<\/p>\n<h4><br \/><strong>Une fois que l\u2019on sait tout cela, que fait-on? Par o\u00f9 commence-t-on?<\/strong><\/h4>\n<p><b><\/b>Pour t\u2019aider \u00e0 r\u00e9pondre \u00e0 ces questions, les intervenants du Carrefour jeunesse-emploi Saint-Hubert peuvent t\u2019aider. Que ce soit pour t\u2019accompagner dans la cr\u00e9ation de ton portfolio, dans l\u2019\u00e9laboration de ton plan pour lancer ta carri\u00e8re d\u2019artiste ou dans l\u2019exploration des diff\u00e9rentes formations dans le domaine des arts visuels, nous sommes l\u00e0 pour t\u2019aider.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Vocation en Art!<\/strong><b><br \/><\/b>De plus, chaque automne, afin de conscientiser les jeunes adultes aux r\u00e9alit\u00e9s de la vocation artistique, les diff\u00e9rents Carrefours de la Mont\u00e9r\u00e9gie offrent aux jeunes artistes une vitrine pour exposer leurs \u0153uvres ainsi que des outils permettant d\u2019entamer une d\u00e9marche de professionnalisation de leur art. Tu r\u00eaves d\u2019un avenir professionnel qui met en valeur ta cr\u00e9ativit\u00e9? Ose une carri\u00e8re dans le domaine des arts visuels. C\u2019est avec plaisir que nous t\u2019accompagnerons dans la r\u00e9alisation de tes ambitions!<\/p>\n<p>\u00a0<\/p>\n<h6>Par Karine Drapeau, conseill\u00e8re d&#8217;orientation au CJESH<\/h6>\n<div>\n<p><\/p>\n<\/div>\n<p><!-- \/wp:group --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.<\/p>\n","protected":false},"author":5,"featured_media":4761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-4998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-de-blogue"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"J\u00e9r\u00f4me\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CJESH - Le CJESH, la porte d&#039;entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH\" \/>\n\t\t<meta property=\"og:description\" content=\"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-29T19:51:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-14T15:09:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#blogposting\",\"name\":\"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH\",\"headline\":\"Est-il possible de gagner sa vie dans le domaine des arts visuels?\",\"author\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Page-projet-Vocation-en-art.png\",\"width\":720,\"height\":720},\"datePublished\":\"2021-10-29T19:51:00+00:00\",\"dateModified\":\"2022-01-14T15:09:32+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#webpage\"},\"articleSection\":\"Articles de blogue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cjesh.org\\\/dev\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"name\":\"Articles de blogue\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"position\":2,\"name\":\"Articles de blogue\",\"item\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#listItem\",\"name\":\"Est-il possible de gagner sa vie dans le domaine des arts visuels?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#listItem\",\"position\":3,\"name\":\"Est-il possible de gagner sa vie dans le domaine des arts visuels?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/category\\\/articles-de-blogue\\\/#listItem\",\"name\":\"Articles de blogue\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\",\"name\":\"CJESH\",\"description\":\"Le CJESH, la porte d'entr\\u00e9e pour les 16 \\u00e0 35 ans de Saint-Hubert.\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/CJESH_Logo_Officiel_noir-2048x978-1.png\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/\",\"name\":\"J\\u00e9r\\u00f4me\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7888bff20ae315f9f8ded88b9b8de8922ae8a8ebe5a576bcda9d468ebde545d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"J\\u00e9r\\u00f4me\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#webpage\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/\",\"name\":\"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH\",\"description\":\"Tu aimes dessiner, peindre, sculpter ou peut-\\u00eatre m\\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \\u00e0 vivre de ton art. Eh bien, c\\u2019est peut-\\u00eatre plus accessible que tu ne le crois.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/author\\\/admin1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Page-projet-Vocation-en-art.png\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#mainImage\",\"width\":720,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\\\/#mainImage\"},\"datePublished\":\"2021-10-29T19:51:00+00:00\",\"dateModified\":\"2022-01-14T15:09:32+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#website\",\"url\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/\",\"name\":\"CJESH\",\"description\":\"Le CJESH, la porte d'entr\\u00e9e pour les 16 \\u00e0 35 ans de Saint-Hubert.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/cjesh.org\\\/dev\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH","description":"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.","canonical_url":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/","robots":"noindex, nofollow, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#blogposting","name":"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH","headline":"Est-il possible de gagner sa vie dans le domaine des arts visuels?","author":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"publisher":{"@id":"https:\/\/cjesh.org\/dev\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2021\/11\/Page-projet-Vocation-en-art.png","width":720,"height":720},"datePublished":"2021-10-29T19:51:00+00:00","dateModified":"2022-01-14T15:09:32+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#webpage"},"isPartOf":{"@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#webpage"},"articleSection":"Articles de blogue"},{"@type":"BreadcrumbList","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev#listItem","position":1,"name":"Accueil","item":"https:\/\/cjesh.org\/dev","nextItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","name":"Articles de blogue"}},{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","position":2,"name":"Articles de blogue","item":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/","nextItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#listItem","name":"Est-il possible de gagner sa vie dans le domaine des arts visuels?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#listItem","position":3,"name":"Est-il possible de gagner sa vie dans le domaine des arts visuels?","previousItem":{"@type":"ListItem","@id":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/#listItem","name":"Articles de blogue"}}]},{"@type":"Organization","@id":"https:\/\/cjesh.org\/dev\/#organization","name":"CJESH","description":"Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","url":"https:\/\/cjesh.org\/dev\/","logo":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2021\/11\/CJESH_Logo_Officiel_noir-2048x978-1.png","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#organizationLogo"},"image":{"@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author","url":"https:\/\/cjesh.org\/dev\/author\/admin1\/","name":"J\u00e9r\u00f4me","image":{"@type":"ImageObject","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f7888bff20ae315f9f8ded88b9b8de8922ae8a8ebe5a576bcda9d468ebde545d?s=96&d=mm&r=g","width":96,"height":96,"caption":"J\u00e9r\u00f4me"}},{"@type":"WebPage","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#webpage","url":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/","name":"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH","description":"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/cjesh.org\/dev\/#website"},"breadcrumb":{"@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#breadcrumblist"},"author":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"creator":{"@id":"https:\/\/cjesh.org\/dev\/author\/admin1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/cjesh.org\/dev\/wp-content\/uploads\/2021\/11\/Page-projet-Vocation-en-art.png","@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#mainImage","width":720,"height":720},"primaryImageOfPage":{"@id":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/#mainImage"},"datePublished":"2021-10-29T19:51:00+00:00","dateModified":"2022-01-14T15:09:32+00:00"},{"@type":"WebSite","@id":"https:\/\/cjesh.org\/dev\/#website","url":"https:\/\/cjesh.org\/dev\/","name":"CJESH","description":"Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/cjesh.org\/dev\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"CJESH - Le CJESH, la porte d'entr\u00e9e pour les 16 \u00e0 35 ans de Saint-Hubert.","og:type":"article","og:title":"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH","og:description":"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois.","og:url":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/","article:published_time":"2021-10-29T19:51:00+00:00","article:modified_time":"2022-01-14T15:09:32+00:00","twitter:card":"summary","twitter:title":"Est-il possible de gagner sa vie dans le domaine des arts visuels? - CJESH","twitter:description":"Tu aimes dessiner, peindre, sculpter ou peut-\u00eatre m\u00eame faire de la photographie, mais tu te demandes comment tu pourrais bien parvenir \u00e0 vivre de ton art. Eh bien, c\u2019est peut-\u00eatre plus accessible que tu ne le crois."},"aioseo_meta_data":{"post_id":"4998","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-10 19:53:34","updated":"2025-06-04 09:37:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cjesh.org\/dev\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/\" title=\"Articles de blogue\">Articles de blogue<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEst-il possible de gagner sa vie dans le domaine des arts visuels?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/cjesh.org\/dev"},{"label":"Articles de blogue","link":"https:\/\/cjesh.org\/dev\/category\/articles-de-blogue\/"},{"label":"Est-il possible de gagner sa vie dans le domaine des arts visuels?","link":"https:\/\/cjesh.org\/dev\/est-il-possible-de-gagner-sa-vie-dans-le-domaine-des-arts-visuels\/"}],"_links":{"self":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/4998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/comments?post=4998"}],"version-history":[{"count":16,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/4998\/revisions"}],"predecessor-version":[{"id":5328,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/posts\/4998\/revisions\/5328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/media\/4761"}],"wp:attachment":[{"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/media?parent=4998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/categories?post=4998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cjesh.org\/dev\/wp-json\/wp\/v2\/tags?post=4998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}